{"id":23,"date":"2014-05-07T16:24:32","date_gmt":"2014-05-07T07:24:32","guid":{"rendered":"http:\/\/ad115w3wfs.smartrelease.jp\/kawamuraGakuen\/syougaku\/news\/post_13.html"},"modified":"2014-05-07T16:24:32","modified_gmt":"2014-05-07T07:24:32","slug":"post_13","status":"publish","type":"post","link":"https:\/\/ad115w3wfs.smartrelease.jp\/syougaku\/2014\/05\/07\/23\/","title":{"rendered":"\u30b0\u30e9\u30a6\u30f3\u30c9\u3067\u6d3b\u52d5\u3057\u307e\u3057\u305f"},"content":{"rendered":"\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img src=\"http:\/\/ad115w3wfs.smartrelease.jp\/kawamuraGakuen\/syougaku\/wp-content\/uploads\/sites\/3\/2014\/05\/n_syou_140507.jpg\" alt=\"\" class=\"wp-image-925\" \/><\/figure><\/div>\n\n\n\n<ul class=\"txt-list\"><li><strong>\u5e73\u621026\u5e745\u67087\u65e5 \u9db4\u53cb\u4f1a\u30af\u30e9\u30d6\u6d3b\u52d5<\/strong><\/li><\/ul>\n\n\n\n<p> \uff11\u3064\u306e\u30dc\u30fc\u30eb\u3092\u8ffd\u3044\u304b\u3051\u3001\u30b0\u30e9\u30a6\u30f3\u30c9\u3092\u304b\u3051\u307e\u308f\u308a\u307e\u3057\u305f\u3002 <\/p>\n\n\n\n<p>\u4e94\u6708\u6674\u308c\u306e\u4eca\u65e5\u306f\u3001\uff12\u56de\u76ee\u306e\u30af\u30e9\u30d6\u6d3b\u52d5\u3067\u3057\u305f\u3002\u4e2d\u9ad8\u306e\u5e83\u3044\u65bd\u8a2d\u3092\u4f7f\u3048\u308b\u306e\u3082\u9b45\u529b\u7684\u306a\u6d3b\u52d5\u3067\u3059\u3002 <\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u5e73\u621026\u5e745\u67087\u65e5 \u9db4\u53cb\u4f1a\u30af\u30e9\u30d6\u6d3b\u52d5 \uff11\u3064\u306e\u30dc\u30fc\u30eb\u3092\u8ffd\u3044\u304b\u3051\u3001\u30b0\u30e9\u30a6\u30f3\u30c9\u3092\u304b\u3051\u307e\u308f\u308a\u307e\u3057\u305f\u3002 \u4e94\u6708\u6674\u308c\u306e\u4eca\u65e5\u306f\u3001\uff12\u56de\u76ee\u306e\u30af\u30e9\u30d6\u6d3b\u52d5\u3067\u3057\u305f\u3002\u4e2d\u9ad8\u306e\u5e83\u3044\u65bd\u8a2d\u3092\u4f7f\u3048\u308b\u306e\u3082\u9b45\u529b\u7684\u306a\u6d3b\u52d5\u3067\u3059\u3002<\/p>\n","protected":false},"author":1,"featured_media":11877,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/ad115w3wfs.smartrelease.jp\/syougaku\/wp-json\/wp\/v2\/posts\/23"}],"collection":[{"href":"https:\/\/ad115w3wfs.smartrelease.jp\/syougaku\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ad115w3wfs.smartrelease.jp\/syougaku\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ad115w3wfs.smartrelease.jp\/syougaku\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ad115w3wfs.smartrelease.jp\/syougaku\/wp-json\/wp\/v2\/comments?post=23"}],"version-history":[{"count":0,"href":"https:\/\/ad115w3wfs.smartrelease.jp\/syougaku\/wp-json\/wp\/v2\/posts\/23\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ad115w3wfs.smartrelease.jp\/syougaku\/wp-json\/wp\/v2\/media\/11877"}],"wp:attachment":[{"href":"https:\/\/ad115w3wfs.smartrelease.jp\/syougaku\/wp-json\/wp\/v2\/media?parent=23"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ad115w3wfs.smartrelease.jp\/syougaku\/wp-json\/wp\/v2\/categories?post=23"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ad115w3wfs.smartrelease.jp\/syougaku\/wp-json\/wp\/v2\/tags?post=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}